{"id":660883,"date":"2023-04-04T09:25:07","date_gmt":"2023-04-04T02:25:07","guid":{"rendered":"https:\/\/www.matichonweekly.com\/?p=660883"},"modified":"2023-04-04T09:25:07","modified_gmt":"2023-04-04T02:25:07","slug":"%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b9%88%e0%b8%b2%e0%b8%aa%e0%b8%99%e0%b9%83%e0%b8%88-%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%95%e0%b9%89","status":"publish","type":"post","link":"https:\/\/www.matichon.co.th\/weekly\/column\/article_660883","title":{"rendered":"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08  \u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e32"},"content":{"rendered":"<p><strong>\u0e04\u0e25\u0e38\u0e01\u0e27\u0e07\u0e43\u0e19 | \u0e1e\u0e34\u0e28\u0e13\u0e38 \u0e19\u0e34\u0e25\u0e01\u0e25\u0e31\u0e14<\/strong><\/p>\n<p><strong>Facebook : @Pitsanuofficial<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08<\/strong><\/p>\n<p><strong>\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e32<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>\u0e08\u0e35\u0e40\u0e0b\u0e25 \u0e1a\u0e38\u0e19\u0e14\u0e4c\u0e40\u0e0a\u0e48\u0e19 (Gisele Bundchen) \u0e19\u0e32\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e16\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01\u0e0a\u0e32\u0e27\u0e1a\u0e23\u0e32\u0e0b\u0e34\u0e25 \u0e27\u0e31\u0e22 42 \u0e1b\u0e35 \u0e2d\u0e14\u0e35\u0e15\u0e20\u0e23\u0e23\u0e22\u0e32\u0e02\u0e2d\u0e07\u0e17\u0e2d\u0e21 \u0e40\u0e1a\u0e23\u0e14\u0e35\u0e49 (Tom Brady) \u0e22\u0e2d\u0e14\u0e19\u0e31\u0e01\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25 \u0e15\u0e4d\u0e32\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e47\u0e01\u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e25\u0e02\u0e2d\u0e07 NFL \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e0a\u0e21\u0e1b\u0e4c Super Bowl 7 \u0e2a\u0e21\u0e31\u0e22<\/p>\n<p>\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e07\u0e41\u0e1a\u0e1a\u0e42\u0e06\u0e29\u0e13\u0e32\u0e43\u0e19\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d Arezzo \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e2d\u0e34\u0e15\u0e32\u0e25\u0e35 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e47\u0e01\u0e0a\u0e31\u0e48\u0e19\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27 2023<\/p>\n<p>\u0e43\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 \u0e08\u0e35\u0e40\u0e0b\u0e25\u0e2a\u0e27\u0e21\u0e0a\u0e38\u0e14\u0e1a\u0e2d\u0e14\u0e35\u0e49\u0e2a\u0e39\u0e17\u0e2a\u0e35\u0e14\u0e4d\u0e32 \u0e02\u0e32\u0e40\u0e27\u0e49\u0e32\u0e2a\u0e39\u0e07\u0e21\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e21\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e1a\u0e39\u0e4a\u0e15\u0e2a\u0e35\u0e14\u0e4d\u0e32\u0e2a\u0e39\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e40\u0e02\u0e48\u0e32<\/p>\n<p>\u0e42\u0e0a\u0e27\u0e4c\u0e25\u0e35\u0e25\u0e32\u0e2a\u0e38\u0e14\u0e40\u0e0b\u0e47\u0e01\u0e0b\u0e35\u0e48\u0e40\u0e15\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e32\u0e2b\u0e23\u0e37\u0e2d Pole dance (\u0e42\u0e1e\u0e25\u0e41\u0e14\u0e19\u0e0b\u0e4c)<\/p>\n<div id=\"attachment_660886\" style=\"width: 1090px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-660886\" class=\"size-full wp-image-660886\" src=\"https:\/\/www.matichonweekly.com\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-1.jpg\" alt=\"\" width=\"1080\" height=\"1350\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-1.jpg 1080w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-1-240x300.jpg 240w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-1-819x1024.jpg 819w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-1-768x960.jpg 768w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-1-696x870.jpg 696w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-1-336x420.jpg 336w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><p id=\"caption-attachment-660886\" class=\"wp-caption-text\">\u0e08\u0e35\u0e40\u0e0b\u0e25 \u0e1a\u0e38\u0e19\u0e14\u0e4c\u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e15\u0e49\u0e19 Pole dance<\/p><\/div>\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07 Pole dance \u0e2a\u0e34\u0e48\u0e07\u0e41\u0e23\u0e01\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e19\u0e36\u0e01\u0e16\u0e36\u0e07\u0e04\u0e37\u0e2d\u0e20\u0e32\u0e1e\u0e2a\u0e32\u0e27\u0e2a\u0e38\u0e14\u0e40\u0e0b\u0e47\u0e01\u0e0b\u0e35\u0e48\u0e43\u0e19\u0e04\u0e25\u0e31\u0e1a \u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e40\u0e15\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e32\u0e14\u0e49\u0e27\u0e22\u0e17\u0e48\u0e32\u0e17\u0e32\u0e07\u0e40\u0e22\u0e49\u0e32\u0e22\u0e27\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e19\u0e49\u0e2d\u0e22\u0e0a\u0e34\u0e49\u0e19<\/p>\n<p>\u0e19\u0e31\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e1e\u0e08\u0e4d\u0e32\u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15\u0e17\u0e35\u0e48\u0e17\u0e4d\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e21\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e17\u0e35\u0e48\u0e40\u0e15\u0e49\u0e19 Pole dance \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e17\u0e4d\u0e32\u0e07\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e04\u0e37\u0e19 \u0e44\u0e23\u0e49\u0e23\u0e2a\u0e19\u0e34\u0e22\u0e21<\/p>\n<p>\u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e43\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 Crunch (\u0e04\u0e23\u0e31\u0e49\u0e19\u0e0a\u0e4c) \u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e22\u0e34\u0e21\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e44\u0e14\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e19\u0e4d\u0e32 Pole dance \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1b\u0e35 2004 \u0e01\u0e47\u0e40\u0e25\u0e22\u0e21\u0e35\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e27\u0e34\u0e1e\u0e32\u0e01\u0e29\u0e4c\u0e27\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c\u0e15\u0e32\u0e21\u0e21\u0e32\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19\u0e17\u0e35\u0e48\u0e04\u0e19\u0e2b\u0e21\u0e01\u0e21\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e21\u0e32\u0e23\u0e21\u0e13\u0e4c<\/p>\n<p>\u0e21\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e01 Pole dance \u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e35\u0e2c\u0e32<\/p>\n<p>\u0e41\u0e15\u0e48\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22 Pole dance \u0e01\u0e47\u0e44\u0e14\u0e49\u0e15\u0e48\u0e2d\u0e2a\u0e39\u0e49\u0e41\u0e25\u0e30\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19 Pole dance \u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21<\/p>\n<div id=\"attachment_660887\" style=\"width: 1090px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-660887\" class=\"size-full wp-image-660887\" src=\"https:\/\/www.matichonweekly.com\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-2.jpg\" alt=\"\" width=\"1080\" height=\"721\" data-has-syndication-rights=\"1\" data-portal-copyright=\"Matichon Public Co.,Ltd.\" srcset=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-2.jpg 1080w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-2-300x200.jpg 300w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-2-1024x684.jpg 1024w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-2-768x513.jpg 768w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-2-696x465.jpg 696w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2023\/03\/\u0e1e\u0e34\u0e28\u0e13\u0e38-2-629x420.jpg 629w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><p id=\"caption-attachment-660887\" class=\"wp-caption-text\">\u0e21\u0e31\u0e25\u0e25\u0e32\u0e02\u0e32\u0e21\u0e1a\u0e4c \u0e02\u0e2d\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22<\/p><\/div>\n<p>\u0e40\u0e04\u0e18\u0e35\u0e48 \u0e42\u0e04\u0e17\u0e2a\u0e4c (Katie Coates) \u0e1c\u0e39\u0e49\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e14\u0e4d\u0e32\u0e23\u0e07\u0e15\u0e4d\u0e32\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e2b\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e40\u0e2a\u0e32\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 (International Pole Sports Federation : IPSF) \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e23\u0e39\u0e2a\u0e2d\u0e19 Pole dance \u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19 Pole dance \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48\u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19\u0e22\u0e31\u0e48\u0e27\u0e22\u0e27\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08<\/p>\n<p>\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e2d\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e08\u0e21\u0e32\u0e14\u0e39\u0e40\u0e2d\u0e07\u0e08\u0e36\u0e07\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19 Pole dance \u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e30\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e21\u0e2b\u0e32\u0e28\u0e32\u0e25<\/p>\n<p>\u0e04\u0e19\u0e17\u0e35\u0e48\u0e40\u0e15\u0e49\u0e19 Pole dance \u0e08\u0e30\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e14\u0e49\u0e1d\u0e36\u0e01\u0e1d\u0e19\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e2a\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19<\/p>\n<p>\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2b\u0e38\u0e48\u0e19\u0e1f\u0e34\u0e15\u0e41\u0e25\u0e30\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e17\u0e4d\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e48\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e40\u0e0b\u0e47\u0e01\u0e0b\u0e35\u0e48\u0e41\u0e25\u0e30\u0e21\u0e35\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e40\u0e15\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n<p>\u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19 Pole dance \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e22\u0e34\u0e21\u0e19\u0e32\u0e2a\u0e15\u0e34\u0e01<\/p>\n<p>\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e04\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e48\u0e19 Pole dance \u0e15\u0e32\u0e21\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a\u0e41\u0e25\u0e30\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e47\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e01\u0e0b\u0e35\u0e48\u0e2a\u0e27\u0e21\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e2a\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e15\u0e49\u0e19\u0e01\u0e31\u0e19\u0e15\u0e32\u0e21\u0e04\u0e25\u0e31\u0e1a\u0e43\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e01\u0e48\u0e2d\u0e19<\/p>\n<p>&nbsp;<\/p>\n<p>\u0e01\u0e27\u0e48\u0e32 20 \u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 Pole dance \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e43\u0e19\u0e2b\u0e21\u0e39\u0e48\u0e2a\u0e32\u0e27\u0e46 \u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/p>\n<p>\u0e21\u0e35\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22 Pole dance<\/p>\n<p>\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 Pole dance \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e08\u0e23\u0e34\u0e07\u0e08\u0e31\u0e07\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22<\/p>\n<p>\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e21\u0e35\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e17\u0e35\u0e48\u0e14\u0e35\u0e27\u0e48\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19 Pole dance \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e0a\u0e34\u0e07\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e42\u0e2d\u0e25\u0e34\u0e21\u0e1b\u0e34\u0e01\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15<\/p>\n<p>\u0e14\u0e23. \u0e21\u0e34\u0e2a\u0e15\u0e35\u0e49 \u0e2d\u0e2d\u0e2a\u0e15\u0e34\u0e19 (Dr. Misty Austin) \u0e19\u0e31\u0e01\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e4d\u0e32\u0e1a\u0e31\u0e14\u0e41\u0e25\u0e30\u0e04\u0e23\u0e39\u0e2a\u0e2d\u0e19\u0e17\u0e48\u0e27\u0e07\u0e17\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 (Movement Coach) \u0e40\u0e23\u0e35\u0e22\u0e01 Pole dance \u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07<\/p>\n<p>\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e41\u0e19\u0e30\u0e19\u0e4d\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07 Pole dance \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e14\u0e49\u0e27\u0e22<\/p>\n<p>&nbsp;<\/p>\n<p>\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07 Pole dance \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1c\u0e32\u0e1c\u0e25\u0e32\u0e0d\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e25\u0e30 250-350 \u0e41\u0e04\u0e25\u0e2d\u0e23\u0e35 \u0e1e\u0e2d\u0e46 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32 30 \u0e19\u0e32\u0e17\u0e35<\/p>\n<p>\u0e41\u0e21\u0e49\u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e21\u0e32\u0e01\u0e43\u0e19\u0e2b\u0e21\u0e39\u0e48\u0e2a\u0e32\u0e27\u0e46 \u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27\u0e17\u0e35\u0e48\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e4d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e32\u0e19\u0e35\u0e49\u0e21\u0e35\u0e15\u0e49\u0e19\u0e01\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e27\u0e48\u0e32 800 \u0e1b\u0e35\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27<\/p>\n<p>\u0e42\u0e14\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e19\u0e43\u0e19\u0e0a\u0e37\u0e48\u0e2d \u0e21\u0e31\u0e25\u0e25\u0e32\u0e02\u0e32\u0e21\u0e1a\u0e4c (Mallakhamb) \u0e0b\u0e36\u0e48\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21\u0e2d\u0e22\u0e39\u0e48<\/p>\n<p>\u0e41\u0e15\u0e48\u0e15\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01 Pole Dance Fitness \u0e1c\u0e39\u0e49\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e49\u0e19\u0e17\u0e48\u0e32\u0e17\u0e32\u0e07\u0e40\u0e01\u0e32\u0e30\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e2a\u0e32\u0e41\u0e19\u0e27\u0e22\u0e34\u0e21\u0e19\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e14\u0e39\u0e27\u0e32\u0e1a\u0e2b\u0e27\u0e34\u0e27\u0e40\u0e0b\u0e47\u0e01\u0e0b\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e1a Pole Dance Fitness<\/p>\n<p>\u0e04\u0e4d\u0e32\u0e27\u0e48\u0e32 \u0e21\u0e31\u0e25\u0e25\u0e32\u0e02\u0e32\u0e21\u0e1a\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e04\u0e4d\u0e32\u0e27\u0e48\u0e32 &#8220;\u0e21\u0e31\u0e25\u0e25\u0e32 (malla)&#8221; \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e19\u0e31\u0e01\u0e01\u0e32\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e32\u0e22\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e2a\u0e48\u0e27\u0e19\u0e04\u0e4d\u0e32\u0e27\u0e48\u0e32 &#8220;\u0e02\u0e32\u0e21\u0e1a\u0e4c (khamb)&#8221; \u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07 \u0e40\u0e2a\u0e32<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"th\" dir=\"ltr\">\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e09\u0e31\u0e1a\u0e44\u0e27 \u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 \u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e21\u0e15\u0e34\u0e0a\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<a href=\"https:\/\/t.co\/KYFMEpsHWj\" target=\"_blank\">https:\/\/t.co\/KYFMEpsHWj<\/a><\/p>\n<p>&mdash; MatichonWeekly \u0e21\u0e15\u0e34\u0e0a\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c (@matichonweekly) <a href=\"https:\/\/twitter.com\/matichonweekly\/status\/1552197630306177024?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 27, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e25\u0e38\u0e01\u0e27\u0e07\u0e43\u0e19 | \u0e1e\u0e34\u0e28\u0e13\u0e38 \u0e19\u0e34\u0e25\u0e01\u0e25\u0e31\u0e14 Facebook : @Pitsanuofficial &#038;n [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":660888,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,574],"tags":[33053,33052,33276,33010],"msn":[],"line":[466],"class_list":["post-660883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-column","category-pitsanu","tag-33053","tag-33052","tag-pole-dance","tag-33010","line-prod"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/660883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/comments?post=660883"}],"version-history":[{"count":0,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/660883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/media\/660888"}],"wp:attachment":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/media?parent=660883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/categories?post=660883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/tags?post=660883"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/msn?post=660883"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/line?post=660883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}