{"id":858750,"date":"2025-09-14T10:00:00","date_gmt":"2025-09-14T03:00:00","guid":{"rendered":"https:\/\/www.matichon.co.th\/weekly\/?p=858750"},"modified":"2025-09-14T10:00:10","modified_gmt":"2025-09-14T03:00:10","slug":"%e0%b8%97%e0%b8%b3%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%9a","status":"publish","type":"post","link":"https:\/\/www.matichon.co.th\/weekly\/column\/article_858750","title":{"rendered":"\u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u0e2a\u0e33\u0e40\u0e23\u0e34\u0e07\u0e04\u0e14\u0e35 | \u0e17\u0e23\u0e07\u0e27\u0e32\u0e14<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e04\u0e23\u0e2d\u0e07\u0e04\u0e07\u0e14\u0e33\u0e23\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e23\u0e31\u0e0a\u0e17\u0e32\u0e22\u0e32\u0e17\u0e25\u0e33\u0e14\u0e31\u0e1a 3 \u0e41\u0e2b\u0e48\u0e07\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e25\u0e25\u0e31\u0e07\u0e01\u0e4c\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e15\u0e48\u0e2d\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e30\u0e1a\u0e34\u0e14\u0e32&#8230;\u0e1b\u0e23\u0e34\u0e19\u0e0b\u0e4c\u0e27\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e1e\u0e23\u0e30\u0e40\u0e0a\u0e29\u0e10\u0e32&#8230;\u0e1b\u0e23\u0e34\u0e19\u0e0b\u0e4c\u0e08\u0e2d\u0e23\u0e4c\u0e08 \u0e1b\u0e23\u0e34\u0e19\u0e40\u0e0b\u0e2a\u0e0a\u0e32\u0e23\u0e4c\u0e25\u0e2d\u0e15 \u0e01\u0e47\u0e21\u0e31\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e32\u0e22\u0e15\u0e32\u0e08\u0e31\u0e1a\u0e08\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e0a\u0e19\u0e40\u0e2a\u0e21\u0e2d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e34\u0e19\u0e0b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e34\u0e19\u0e40\u0e0b\u0e2a\u0e2d\u0e2d\u0e1f\u0e40\u0e27\u0e25\u0e2a\u0e4c\u0e40\u0e2a\u0e14\u0e47\u0e08\u0e44\u0e1b\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a\u0e27\u0e34\u0e21\u0e40\u0e1a\u0e34\u0e25\u0e14\u0e31\u0e19 2025 \u0e23\u0e2d\u0e1a\u0e0a\u0e34\u0e07\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e0a\u0e32\u0e22\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27 \u0e04\u0e23\u0e32\u0e15\u0e49\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1b\u0e23\u0e34\u0e19\u0e0b\u0e4c\u0e08\u0e2d\u0e08\u0e23\u0e4c\u0e08 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e34\u0e19\u0e40\u0e0b\u0e2a\u0e0a\u0e32\u0e23\u0e4c\u0e25\u0e2d\u0e15\u0e42\u0e14\u0e22\u0e40\u0e2a\u0e14\u0e47\u0e08\u0e14\u0e49\u0e27\u0e22 \u0e1b\u0e23\u0e30\u0e14\u0e32\u0e41\u0e1f\u0e19\u0e04\u0e25\u0e31\u0e1a\u0e15\u0e31\u0e1a\u0e15\u0e34\u0e48\u0e07\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e07\u0e28\u0e4c\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e27\u0e01\u0e0b\u0e39\u0e2e\u0e01\u0e01\u0e35\u0e2c\u0e32\u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a \u0e08\u0e36\u0e07\u0e1b\u0e25\u0e37\u0e49\u0e21\u0e40\u0e1b\u0e23\u0e21\u0e40\u0e01\u0e29\u0e21\u0e42\u0e2a\u0e21\u0e19\u0e31\u0e2a<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e0d\u0e34\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e23\u0e07\u0e2a\u0e27\u0e21\u0e0a\u0e38\u0e14\u0e2a\u0e35\u0e04\u0e23\u0e35\u0e21\u0e01\u0e38\u0e4a\u0e19\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d MARY JANE \u0e41\u0e27\u0e48\u0e19\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e40\u0e01\u0e4b \u0e41\u0e25\u0e30\u0e16\u0e31\u0e01\u0e40\u0e1b\u0e35\u0e22\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e21\u0e41\u0e1a\u0e1a FRENCH BRAIDS \u0e2a\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e07\u0e41\u0e19\u0e1a\u0e28\u0e35\u0e23\u0e29\u0e30 \u0e41\u0e15\u0e48\u0e17\u0e35\u0e48\u0e41\u0e1f\u0e19\u0e04\u0e25\u0e31\u0e1a\u0e2e\u0e37\u0e2d\u0e2e\u0e32\u0e01\u0e31\u0e19\u0e02\u0e23\u0e21\u0e0a\u0e21\u0e0a\u0e2d\u0e1a \u0e01\u0e47\u0e04\u0e37\u0e2d \u0e17\u0e23\u0e07\u0e17\u0e32\u0e40\u0e25\u0e47\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e35\u0e0a\u0e21\u0e1e\u0e39\u0e2b\u0e27\u0e32\u0e19\u0e43\u0e2a \u0e2a\u0e30\u0e2d\u0e49\u0e32\u0e19\u0e15\u0e32<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2b\u0e15\u0e38\u0e17\u0e35\u0e48\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e1b\u0e23\u0e34\u0e19\u0e0b\u0e4c\u0e2d\u0e2d\u0e1f\u0e40\u0e27\u0e25\u0e2a\u0e4c\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e19 ROYAL BOX \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e2d\u0e31\u0e12\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e2a\u0e32\u0e22\u0e15\u0e32\u0e41\u0e25\u0e30\u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e19\u0e31\u0e1a\u0e44\u0e21\u0e48\u0e16\u0e49\u0e27\u0e19\u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e17\u0e23\u0e07\u0e2a\u0e19\u0e38\u0e01\u0e2a\u0e19\u0e32\u0e19 \u0e2a\u0e33\u0e23\u0e32\u0e0d\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e21\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e4c\u0e40\u0e01\u0e21<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e43\u0e04\u0e23\u0e1a\u0e32\u0e07\u0e04\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e02\u0e49\u0e2d\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e17\u0e32\u0e40\u0e25\u0e47\u0e1a\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e19\u0e40\u0e0b\u0e2a\u0e0a\u0e32\u0e23\u0e4c\u0e25\u0e2d\u0e15 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e27\u0e01\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e07\u0e28\u0e4c \u0e41\u0e15\u0e48\u0e1e\u0e23\u0e30\u0e21\u0e32\u0e23\u0e14\u0e32\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a \u0e41\u0e04\u0e17\u0e40\u0e18\u0e2d\u0e23\u0e35\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e21\u0e48\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e25\u0e39\u0e01\u0e46&#8221; \u0e1e\u0e23\u0e30\u0e2a\u0e2b\u0e32\u0e22\u0e04\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1a\u0e2d\u0e01\u0e01\u0e31\u0e1a PEOPLE<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e07\u0e28\u0e4c\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e47\u0e1e\u0e39\u0e14\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 \u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e0e\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e43\u0e14\u0e46 \u0e27\u0e48\u0e32 \u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e07\u0e28\u0e4c\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e32\u0e40\u0e25\u0e47\u0e1a\u0e01\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e35\u0e43\u0e14<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e15\u0e34\u0e01\u0e32\u0e43\u0e14\u0e46 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e32\u0e40\u0e25\u0e47\u0e1a\u0e2a\u0e35\u0e40\u0e02\u0e49\u0e21\u0e14\u0e49\u0e27\u0e22&#8221; \u0e42\u0e2d\u0e21\u0e34\u0e14 \u0e2a\u0e42\u0e04\u0e1a\u0e35 \u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e19\u0e35\u0e49\u0e04\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e04\u0e22\u0e1a\u0e2d\u0e01\u0e01\u0e31\u0e1a\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23 HARPER BAZAAR \u0e44\u0e27\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e35 2018 \u0e42\u0e19\u0e48\u0e19\u0e41\u0e25\u0e49\u0e27 &#8220;\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e01\u0e47\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e21\u0e35\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e07\u0e28\u0e4c\u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e43\u0e14 \u0e17\u0e32\u0e40\u0e25\u0e47\u0e1a\u0e2a\u0e35\u0e40\u0e02\u0e49\u0e21\u0e08\u0e31\u0e14\u0e46 \u0e40\u0e25\u0e22&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e14\u0e35\u0e15\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e04\u0e27\u0e35\u0e19\u0e40\u0e2d\u0e25\u0e34\u0e0b\u0e32\u0e40\u0e1a\u0e18\u0e17\u0e35\u0e48 2 \u0e01\u0e47\u0e17\u0e23\u0e07\u0e19\u0e34\u0e22\u0e21\u0e17\u0e32\u0e40\u0e25\u0e47\u0e1a\u0e2a\u0e35\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e21\u0e34\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e30\u0e19\u0e02\u0e32\u0e14\u0e39\u0e42\u0e14\u0e14\u0e1c\u0e32\u0e07 \u0e01\u0e23\u0e30\u0e08\u0e30\u0e01\u0e23\u0e30\u0e08\u0e48\u0e32\u0e07\u0e25\u0e39\u0e01\u0e15\u0e32\u0e43\u0e04\u0e23 \u0e27\u0e48\u0e32\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 \u0e17\u0e23\u0e07\u0e40\u0e25\u0e37\u0e01\u0e43\u0e0a\u0e49\u0e2a\u0e35 BALLET SLIPPERS \u0e02\u0e2d\u0e07 ESSIE COLLECTION \u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32 30 \u0e1b\u0e35<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e19\u0e36\u0e48\u0e07 \u0e01\u0e32\u0e23\u0e17\u0e32\u0e40\u0e25\u0e47\u0e1a\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e19\u0e40\u0e0b\u0e2a\u0e0a\u0e32\u0e23\u0e4c\u0e25\u0e2d\u0e15 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e0a\u0e35\u0e49\u0e27\u0e48\u0e32 \u0e17\u0e23\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e27\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e0d\u0e34\u0e07\u0e19\u0e49\u0e2d\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e21\u0e48\u0e19\u0e32\u0e19\u0e21\u0e32\u0e19\u0e35\u0e49\u0e40\u0e04\u0e22\u0e44\u0e14\u0e49\u0e09\u0e32\u0e22\u0e32\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19 Mimi me \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e19\u0e0b\u0e4c\u0e27\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e1e\u0e23\u0e30\u0e1a\u0e34\u0e14\u0e32 \u0e01\u0e47\u0e2a\u0e48\u0e2d\u0e41\u0e27\u0e27\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e2a\u0e07\u0e48\u0e32 \u0e44\u0e1b\u0e02\u0e49\u0e32\u0e07\u0e04\u0e25\u0e31\u0e1a\u0e04\u0e25\u0e49\u0e32\u0e22\u0e1e\u0e23\u0e30\u0e21\u0e32\u0e23\u0e14\u0e32\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e14\u0e31\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e1f\u0e19\u0e04\u0e25\u0e31\u0e1a\u0e42\u0e1e\u0e2a\u0e15\u0e4c\u0e2d\u0e34\u0e19\u0e2a\u0e15\u0e32\u0e41\u0e01\u0e23\u0e21 \u0e0a\u0e21\u0e40\u0e0a\u0e22\u0e01\u0e31\u0e19\u0e0a\u0e37\u0e48\u0e19\u0e43\u0e08 \u0e15\u0e48\u0e2d\u0e17\u0e49\u0e32\u0e22\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e14\u0e47\u0e08\u0e44\u0e1b\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e27\u0e34\u0e21\u0e40\u0e1a\u0e34\u0e25\u0e14\u0e31\u0e19\u0e2b\u0e19\u0e19\u0e35\u0e49 \u0e2d\u0e32\u0e17\u0e34<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;CHARLOTTE LOOKS LIKE HER MUM KATE&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;CHARLOTTE IS STEALING THE SHOW WITH HER MATURE ELEGANCE AND POISE&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e2f\u0e25\u0e2f<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"th\" dir=\"ltr\">\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e09\u0e31\u0e1a\u0e44\u0e27 \u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 \u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e21\u0e15\u0e34\u0e0a\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<a href=\"https:\/\/t.co\/KYFMEpsHWj\" target=\"_blank\">https:\/\/t.co\/KYFMEpsHWj<\/a><\/p>&mdash; MatichonWeekly \u0e21\u0e15\u0e34\u0e0a\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c (@matichonweekly) <a href=\"https:\/\/twitter.com\/matichonweekly\/status\/1552197630306177024?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 27, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e33\u0e40\u0e23\u0e34\u0e07\u0e04\u0e14\u0e35 | \u0e17\u0e23\u0e07\u0e27\u0e32\u0e14 \u0e19\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e04\u0e23\u0e2d\u0e07\u0e04\u0e07\u0e14\u0e33\u0e23\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e23\u0e31\u0e0a\u0e17\u0e32\u0e22\u0e32\u0e17\u0e25\u0e33 [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":858762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15,5,523,38962],"tags":[10752,11772],"msn":[],"line":[],"class_list":["post-858750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-entertainment","category-column","category-entertainment","category-inter","tag-10752","tag-11772"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/858750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/comments?post=858750"}],"version-history":[{"count":3,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/858750\/revisions"}],"predecessor-version":[{"id":859325,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/858750\/revisions\/859325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/media\/858762"}],"wp:attachment":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/media?parent=858750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/categories?post=858750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/tags?post=858750"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/msn?post=858750"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/line?post=858750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}