{"id":859185,"date":"2025-09-16T08:58:55","date_gmt":"2025-09-16T01:58:55","guid":{"rendered":"https:\/\/www.matichon.co.th\/weekly\/?p=859185"},"modified":"2025-09-22T14:07:05","modified_gmt":"2025-09-22T07:07:05","slug":"%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b8%ab%e0%b8%99%e0%b8%b6%e0%b9%88%e0%b8%87%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%96%e0%b8%b6%e0%b8%87%e0%b8%aa%e0%b8%b2%e0%b8%a1-%e0%b9%82%e0%b8%9b","status":"publish","type":"post","link":"https:\/\/www.matichon.co.th\/weekly\/column\/article_859185","title":{"rendered":"\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07\u0e2a\u0e32\u0e21 : \u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29 | \u0e1e\u0e34\u0e18\u0e32 \u0e25\u0e34\u0e49\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e31\u0e15\u0e19\u0e4c<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07\u0e2a\u0e32\u0e21<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>: \u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e19\u0e35\u0e49\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e14\u0e35\u0e40\u0e19\u0e2d\u0e30 \u0e40\u0e25\u0e37\u0e2d\u0e01 1 \u0e44\u0e14\u0e49\u0e16\u0e36\u0e07 3!&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e1c\u0e21\u0e42\u0e1e\u0e25\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01\u0e25\u0e32\u0e07\u0e27\u0e07\u0e01\u0e32\u0e41\u0e1f \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e28\u0e32\u0e25\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d\u0e21\u0e35\u0e04\u0e33\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e41\u0e1e\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23 \u0e0a\u0e34\u0e19\u0e27\u0e31\u0e15\u0e23 \u0e1e\u0e49\u0e19\u0e08\u0e32\u0e01\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1c\u0e21\u0e2b\u0e31\u0e27\u0e40\u0e23\u0e32\u0e30\u0e41\u0e2b\u0e49\u0e07\u0e46 \u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e08\u0e30\u0e15\u0e2d\u0e1a\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e49\u0e19 \u0e08\u0e36\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e08\u0e30\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e08\u0e32\u0e01\u0e23\u0e2d\u0e1a\u0e27\u0e07\u0e1e\u0e39\u0e14\u0e15\u0e48\u0e2d\u0e41\u0e17\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e09\u0e31\u0e19\u0e08\u0e33\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32 You \u0e04\u0e37\u0e2d 29.5 \u0e43\u0e0a\u0e48\u0e44\u0e2b\u0e21? \u0e41\u0e15\u0e48\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e40\u0e02\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e08\u0e30\u0e42\u0e2b\u0e27\u0e15\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e04\u0e19\u0e17\u0e35\u0e48 32 \u0e41\u0e25\u0e49\u0e27\u0e2b\u0e23\u0e37\u0e2d? \u0e20\u0e32\u0e22\u0e43\u0e19 election cycle \u0e40\u0e14\u0e35\u0e22\u0e27? \u0e04\u0e38\u0e49\u0e21\u0e14\u0e35\u0e19\u0e30!&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e04\u0e07\u0e2d\u0e48\u0e32\u0e19\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07 The Financial Times \u0e2b\u0e23\u0e37\u0e2d The New York Times \u0e41\u0e25\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e36\u0e07\u0e41\u0e01\u0e48\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1c\u0e21\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e41\u0e22\u0e49\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e27\u0e48\u0e32 &#8220;\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e21\u0e31\u0e19\u0e01\u0e47\u0e22\u0e38\u0e48\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e2b\u0e25\u0e30&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e22\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e42\u0e14\u0e19\u0e35\u0e40\u0e0b\u0e35\u0e22 \u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e35 \u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e16\u0e39\u0e01\u0e15\u0e31\u0e49\u0e07\u0e04\u0e33\u0e16\u0e32\u0e21\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e0a\u0e38\u0e21\u0e19\u0e38\u0e21\u0e01\u0e25\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e08\u0e32\u0e01\u0e32\u0e23\u0e4c\u0e15\u0e32 \u0e1b\u0e30\u0e17\u0e30\u0e01\u0e31\u0e1a\u0e15\u0e33\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e32\u0e1a\u0e08\u0e25\u0e32\u0e08\u0e25 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e14\u0e31\u0e07\u0e44\u0e1b\u0e17\u0e31\u0e49\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e01\u0e47\u0e22\u0e31\u0e07\u0e22\u0e37\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e23\u0e1a \u0e22\u0e31\u0e07\u0e21\u0e35\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e1e\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e08\u0e23\u0e08\u0e32\u0e01\u0e31\u0e1a\u0e1d\u0e48\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e15\u0e49\u0e32\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e21\u0e48\u0e1e\u0e2d\u0e43\u0e08\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e25\u0e34\u0e48\u0e27 \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e14\u0e34\u0e19\u0e02\u0e1a\u0e27\u0e19\u0e43\u0e19\u0e0b\u0e34\u0e14\u0e19\u0e35\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e21\u0e25\u0e40\u0e1a\u0e34\u0e23\u0e4c\u0e19 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e16\u0e39\u0e01\u0e40\u0e02\u0e22\u0e48\u0e32\u0e41\u0e23\u0e07 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e1c\u0e21\u0e22\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07 2 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1e\u0e32\u0e14\u0e2b\u0e31\u0e27\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e02\u0e48\u0e32\u0e27\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e32\u0e01\u0e25\u0e31\u0e1a\u0e14\u0e39 &#8220;\u0e08\u0e37\u0e14&#8221; \u0e44\u0e1b\u0e40\u0e25\u0e22\u0e43\u0e19\u0e41\u0e07\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e17\u0e49\u0e27\u0e07\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e41\u0e15\u0e48\u0e43\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e04\u0e27\u0e32\u0e21 &#8220;\u0e40\u0e2b\u0e22\u0e34\u0e07&#8221; \u0e41\u0e1a\u0e1a\u0e44\u0e17\u0e22\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e35\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 : \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e21\u0e49\u0e32\u0e2b\u0e21\u0e38\u0e19 (marry go round politics) \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e1b\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e22\u0e38\u0e1a\u0e1e\u0e23\u0e23\u0e04\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e40\u0e25\u0e48\u0e19 \u0e43\u0e0a\u0e49\u0e19\u0e31\u0e01\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e25\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e32\u0e0d \u0e15\u0e31\u0e14\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e40\u0e25\u0e48\u0e19 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e43\u0e19\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"600\" src=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/09\/\u0e1e\u0e34\u0e18\u0e321-2352-1200x600.png\" alt=\"\" class=\"wp-image-859186\" srcset=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/09\/\u0e1e\u0e34\u0e18\u0e321-2352-1200x600.png 1200w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/09\/\u0e1e\u0e34\u0e18\u0e321-2352-768x384.png 768w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/09\/\u0e1e\u0e34\u0e18\u0e321-2352.png 1488w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e25\u0e48\u0e32\u0e21\u0e32\u0e16\u0e36\u0e07\u0e15\u0e23\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e40\u0e25\u0e48\u0e32\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e27\u0e07\u0e01\u0e32\u0e41\u0e1f\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e02\u0e19\u0e07 \u0e2b\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48 \u0e04\u0e37\u0e2d\u0e17\u0e35\u0e48 Harvard Kennedy School \u0e21\u0e35\u0e2b\u0e25\u0e32\u0e22\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e04\u0e39\u0e48\u0e02\u0e19\u0e32\u0e19\u0e01\u0e31\u0e19 \u0e22\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Belfer Center \u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Carr Center \u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e21\u0e19\u0e38\u0e29\u0e22\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e22\u0e38\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21\u0e2a\u0e32\u0e01\u0e25<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Ash Center \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Rajawali Institute for Asia, Indigenous Governance, Reimagine Democracy \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e47\u0e40\u0e15\u0e34\u0e21\u0e40\u0e15\u0e47\u0e21\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e41\u0e25\u0e30\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e48\u0e27\u0e19 Visiting Fellows \u0e41\u0e1a\u0e1a\u0e1c\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19 \u0e01\u0e47\u0e21\u0e32\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 : \u0e1a\u0e32\u0e07\u0e04\u0e19\u0e40\u0e04\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e48\u0e32\u0e27\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07 Bloomberg, \u0e1a\u0e32\u0e07\u0e04\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e14\u0e35\u0e15\u0e1a\u0e23\u0e23\u0e13\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 Wired Magazine \u0e2b\u0e23\u0e37\u0e2d MIT Technology Review, \u0e1a\u0e32\u0e07\u0e04\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e08\u0e32\u0e01 Brown University \u0e2b\u0e23\u0e37\u0e2d Howard University (\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e35\u0e48 Kamala Harris \u0e08\u0e1a), \u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e08\u0e32\u0e01\u0e08\u0e35\u0e19, \u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e01 Foxconn \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e0b\u0e21\u0e34\u0e04\u0e2d\u0e19\u0e14\u0e31\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e15\u0e49\u0e2b\u0e27\u0e31\u0e19, \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e32\u0e01\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e01\u0e32\u0e23\u0e17\u0e39\u0e15\u0e08\u0e32\u0e01\u0e40\u0e21\u0e47\u0e01\u0e0b\u0e34\u0e42\u0e01<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e41\u0e15\u0e48\u0e25\u0e30\u0e04\u0e19\u0e21\u0e35\u0e42\u0e25\u0e01\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e32\u0e21\u0e21\u0e32\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1f\u0e31\u0e07\u0e41\u0e25\u0e49\u0e27\u0e17\u0e31\u0e49\u0e07\u0e40\u0e08\u0e47\u0e1a\u0e41\u0e2a\u0e1a\u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e04\u0e34\u0e14<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/09\/\u0e1e\u0e34\u0e18\u0e322-2352-1200x800.jpg\" alt=\"\" class=\"wp-image-859187\" srcset=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/09\/\u0e1e\u0e34\u0e18\u0e322-2352-1200x800.jpg 1200w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/09\/\u0e1e\u0e34\u0e18\u0e322-2352-768x512.jpg 768w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/09\/\u0e1e\u0e34\u0e18\u0e322-2352-1536x1024.jpg 1536w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/09\/\u0e1e\u0e34\u0e18\u0e322-2352.jpg 1920w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e22\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e33\u0e16\u0e32\u0e21\u0e08\u0e32\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e1c\u0e21 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e17\u0e33\u0e44\u0e21\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e44\u0e17\u0e22\u0e16\u0e36\u0e07\u0e40\u0e1b\u0e23\u0e32\u0e30\u0e1a\u0e32\u0e07\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32?&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e1c\u0e2a\u0e21\u0e21\u0e32\u0e01\u0e1e\u0e23\u0e23\u0e04\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e16\u0e39\u0e01\u0e41\u0e17\u0e23\u0e01\u0e41\u0e0b\u0e07\u0e08\u0e32\u0e01\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e19\u0e2d\u0e01\u0e23\u0e30\u0e1a\u0e1a \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e17\u0e33\u0e44\u0e21\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e16\u0e36\u0e07\u0e16\u0e39\u0e01\u0e1b\u0e25\u0e14\u0e14\u0e49\u0e27\u0e22\u0e04\u0e14\u0e35\u0e08\u0e23\u0e34\u0e22\u0e18\u0e23\u0e23\u0e21\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19?&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e08\u0e23\u0e34\u0e22\u0e18\u0e23\u0e23\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e04\u0e14\u0e35\u0e04\u0e27\u0e32\u0e21 \u0e41\u0e15\u0e48\u0e43\u0e19\u0e44\u0e17\u0e22\u0e01\u0e25\u0e31\u0e1a\u0e16\u0e39\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e27\u0e38\u0e18<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e17\u0e33\u0e44\u0e21\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e16\u0e36\u0e07\u0e16\u0e39\u0e01\u0e25\u0e47\u0e2d\u0e01\u0e44\u0e27\u0e49\u0e08\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e30\u0e2b\u0e21\u0e14\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01?&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e49\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49 bottleneck \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e17\u0e33\u0e44\u0e21\u0e28\u0e32\u0e25\u0e16\u0e36\u0e07\u0e21\u0e35\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e21\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1a\u0e48\u0e2d\u0e22\u0e02\u0e19\u0e32\u0e14\u0e19\u0e31\u0e49\u0e19?&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e16\u0e49\u0e32\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e08\u0e23\u0e34\u0e22\u0e18\u0e23\u0e23\u0e21\u0e17\u0e48\u0e27\u0e21 \u0e41\u0e15\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e41\u0e2b\u0e49\u0e07\u0e1e\u0e2d\u0e14\u0e35? \u0e44\u0e21\u0e48\u0e41\u0e19\u0e48\u0e43\u0e08\u0e1c\u0e21\u0e41\u0e1b\u0e25\u0e16\u0e39\u0e01\u0e40\u0e1b\u0e25\u0e48\u0e32 \u0e41\u0e15\u0e48\u0e40\u0e02\u0e32\u0e1e\u0e39\u0e14\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e19\u0e35\u0e49 (Soaked in virtue while democracy runs dry)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e04\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e21\u0e48\u0e21\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21 \u0e04\u0e07\u0e21\u0e35\u0e04\u0e2d\u0e25\u0e31\u0e21\u0e19\u0e34\u0e2a\u0e15\u0e4c\u0e21\u0e15\u0e34\u0e0a\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e17\u0e48\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e02\u0e35\u0e22\u0e19\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e22\u0e2d\u0e30\u0e41\u0e22\u0e30\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e2b\u0e21\u0e14 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e47\u0e2d\u0e01\u0e44\u0e27\u0e49\u0e43\u0e19\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d 2560<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1c\u0e21\u0e22\u0e31\u0e07\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e0a\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e47\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e19\u0e48\u0e30\u0e41\u0e2b\u0e25\u0e30<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e14\u0e39\u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e0b\u0e14\u0e01\u0e32\u0e41\u0e1f\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e19\u0e16\u0e49\u0e27\u0e22 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e41\u0e22\u0e01\u0e22\u0e49\u0e32\u0e22\u0e01\u0e25\u0e31\u0e1a\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e27\u0e07\u0e40\u0e2d\u0e34\u0e4a\u0e01\u0e2d\u0e4a\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e2a\u0e48\u0e07\u0e17\u0e49\u0e32\u0e22\u0e01\u0e47\u0e04\u0e37\u0e2d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e41\u0e25\u0e49\u0e27\u0e17\u0e33\u0e44\u0e21\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48 1 \u0e16\u0e36\u0e07\u0e21\u0e32\u0e19\u0e31\u0e48\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e25\u0e32\u0e07\u0e42\u0e15\u0e4a\u0e30\u0e19\u0e35\u0e49 \u0e01\u0e25\u0e32\u0e07\u0e41\u0e04\u0e21\u0e1b\u0e31\u0e2a\u0e1a\u0e2d\u0e2a\u0e15\u0e31\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e44\u0e14\u0e49\u0e25\u0e48\u0e30\u0e40\u0e19\u0e35\u0e48\u0e22&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"th\" dir=\"ltr\">\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e09\u0e31\u0e1a\u0e44\u0e27 \u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 \u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e21\u0e15\u0e34\u0e0a\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<a href=\"https:\/\/t.co\/KYFMEpsHWj\" target=\"_blank\">https:\/\/t.co\/KYFMEpsHWj<\/a><\/p>&mdash; MatichonWeekly \u0e21\u0e15\u0e34\u0e0a\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c (@matichonweekly) <a href=\"https:\/\/twitter.com\/matichonweekly\/status\/1552197630306177024?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 27, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29 | \u0e1e\u0e34\u0e18\u0e32 \u0e25\u0e34\u0e49\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07\u0e2a\u0e32\u0e21 : [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":859188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,38984],"tags":[1944,22128],"msn":[],"line":[],"class_list":["post-859185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-column","category-pita","tag-1944","tag-22128"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/859185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/comments?post=859185"}],"version-history":[{"count":3,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/859185\/revisions"}],"predecessor-version":[{"id":860922,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/859185\/revisions\/860922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/media\/859188"}],"wp:attachment":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/media?parent=859185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/categories?post=859185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/tags?post=859185"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/msn?post=859185"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/line?post=859185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}