{"id":875691,"date":"2026-01-08T09:00:00","date_gmt":"2026-01-08T02:00:00","guid":{"rendered":"https:\/\/www.matichon.co.th\/weekly\/?p=875691"},"modified":"2026-01-08T09:00:02","modified_gmt":"2026-01-08T02:00:02","slug":"%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%88-%e0%b8%a1%e0%b8%b2%e0%b9%80%e0%b8%a2%e0%b8%b7%e0%b8%ad%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2-%e0%b8%88%e0%b8%9a","status":"publish","type":"post","link":"https:\/\/www.matichon.co.th\/weekly\/column\/article_875691","title":{"rendered":"\u0e42\u0e15\u0e42\u0e08 \u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e44\u0e17\u0e22 (\u0e08\u0e1a)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>My Country Thailand | \u0e13\u0e31\u0e10\u0e1e\u0e25 \u0e43\u0e08\u0e08\u0e23\u0e34\u0e07<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e42\u0e15\u0e42\u0e08 \u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e44\u0e17\u0e22 (\u0e08\u0e1a)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d 3 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2486 \u0e42\u0e15\u0e42\u0e08 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e15\u0e42\u0e08\u0e19\u0e33\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e43\u0e19\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e04\u0e37\u0e2d \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e15\u0e38\u0e07\u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e43\u0e19\u0e21\u0e25\u0e32\u0e22\u0e39\u0e04\u0e37\u0e2d \u0e44\u0e17\u0e23\u0e1a\u0e38\u0e23\u0e35, \u0e01\u0e25\u0e31\u0e19\u0e15\u0e31\u0e19, \u0e15\u0e23\u0e31\u0e07\u0e01\u0e32\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e1b\u0e30\u0e25\u0e34\u0e2a \u0e21\u0e32\u0e21\u0e2d\u0e1a\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e25\u0e07\u0e19\u0e32\u0e21\u0e43\u0e19\u0e41\u0e16\u0e25\u0e07\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e40\u0e21\u0e37\u0e48\u0e2d 5 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e42\u0e14\u0e22\u0e42\u0e15\u0e42\u0e08\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e08\u0e30\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e40\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e41\u0e25\u0e30\u0e2d\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e32\u0e23\u0e16\u0e19\u0e32\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 (\u0e2a\u0e21\u0e42\u0e0a\u0e04 \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e38\u0e25, 2524, 92-93)<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"848\" height=\"393\" src=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand1-2369.jpg\" alt=\"\" class=\"wp-image-875697\" srcset=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand1-2369.jpg 848w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand1-2369-768x356.jpg 768w\" sizes=\"auto, (max-width: 848px) 100vw, 848px\" \/><figcaption class=\"wp-element-caption\"><em>\u0e42\u0e1b\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e27\u0e07\u0e28\u0e4c\u0e44\u0e1e\u0e1a\u0e39\u0e25\u0e22\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e21\u0e2b\u0e32\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32\u0e02\u0e2d\u0e07\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e43\u0e19\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e21\u0e25\u0e32\u0e22\u0e39 \u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e20\u0e32\u0e1e \u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35\u0e0a\u0e31\u0e22<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1d\u0e48\u0e32\u0e22\u0e44\u0e17\u0e22\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e42\u0e15\u0e42\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35\u0e0a\u0e31\u0e22 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e04\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e04\u0e38\u0e49\u0e19\u0e40\u0e04\u0e22\u0e01\u0e31\u0e19\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e17\u0e19\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e19\u0e38\u0e01\u0e2a\u0e19\u0e32\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e32\u0e01\u0e32\u0e21\u0e39\u0e23\u0e30\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e16\u0e36\u0e07 \u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e27\u0e49\u0e27\u0e48\u0e32<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1a\u0e19\u0e42\u0e15\u0e4a\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e17\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e22\u0e28\u0e1e\u0e31\u0e19\u0e42\u0e17\u0e44\u0e14\u0e49\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e42\u0e15\u0e42\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e41\u0e04\u0e25\u0e48\u0e27\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e15\u0e23\u0e35\u0e43\u0e19\u0e07\u0e32\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e0a\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e40\u0e18\u0e2d\u0e16\u0e32\u0e21\u0e42\u0e15\u0e42\u0e08\u0e27\u0e48\u0e32 \u0e42\u0e15\u0e42\u0e08\u0e0a\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e30\u0e44\u0e23<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e15\u0e42\u0e08\u0e15\u0e2d\u0e1a\u0e27\u0e48\u0e32 \u0e0a\u0e2d\u0e1a\u0e14\u0e37\u0e48\u0e21\u0e01\u0e32\u0e41\u0e1f \u0e43\u0e19\u0e17\u0e31\u0e19\u0e17\u0e35\u0e17\u0e31\u0e19\u0e43\u0e14\u0e19\u0e31\u0e49\u0e19 \u0e17\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e15\u0e2d\u0e1a\u0e27\u0e48\u0e32 &#8220;\u0e14\u0e34\u0e09\u0e31\u0e19\u0e01\u0e47\u0e0a\u0e2d\u0e1a\u0e01\u0e32\u0e41\u0e1f\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e17\u0e35\u0e48\u0e17\u0e48\u0e32\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e14\u0e34\u0e09\u0e31\u0e19\u0e08\u0e30\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e32\u0e41\u0e1f\u0e44\u0e27\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e48\u0e32\u0e19 \u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2f \u0e14\u0e37\u0e48\u0e21\u0e01\u0e32\u0e41\u0e1f\u0e21\u0e32\u0e01\u0e46 \u0e19\u0e30\u0e04\u0e30&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e15\u0e42\u0e08\u0e1f\u0e31\u0e07\u0e41\u0e25\u0e49\u0e27\u0e22\u0e34\u0e49\u0e21 \u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e14\u0e35\u0e43\u0e08\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e19\u0e31\u0e49\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e32\u0e01\u0e32\u0e21\u0e39\u0e23\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32 \u0e1a\u0e38\u0e04\u0e25\u0e34\u0e01\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e1b\u0e0f\u0e34\u0e20\u0e32\u0e13\u0e44\u0e2b\u0e27\u0e1e\u0e23\u0e34\u0e1a\u0e02\u0e2d\u0e07\u0e17\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e2f \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e15\u0e23\u0e35\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e21\u0e32\u0e01<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e15\u0e23\u0e2a\u0e32\u0e27\u0e0a\u0e37\u0e48\u0e2d \u0e08\u0e35\u0e23\u0e27\u0e31\u0e2a\u0e2a\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e32\u0e22\u0e23\u0e49\u0e2d\u0e22\u0e2b\u0e0d\u0e34\u0e07 \u0e41\u0e21\u0e49\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e21\u0e34\u0e44\u0e14\u0e49\u0e41\u0e15\u0e48\u0e07\u0e0a\u0e38\u0e14\u0e17\u0e2b\u0e32\u0e23 \u0e41\u0e15\u0e48\u0e40\u0e02\u0e32\u0e40\u0e04\u0e22\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e15\u0e23\u0e2a\u0e32\u0e27\u0e41\u0e15\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e17\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e14\u0e39\u0e07\u0e32\u0e21\u0e2a\u0e07\u0e48\u0e32\u0e21\u0e32\u0e01<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e42\u0e16\u0e07\u0e17\u0e35\u0e48\u0e42\u0e2d\u0e48\u0e2d\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e2f \u0e0a\u0e48\u0e27\u0e07\u0e2b\u0e31\u0e27\u0e04\u0e48\u0e33\u0e27\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e35\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e1d\u0e48\u0e32\u0e22\u0e44\u0e17\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e \u0e21\u0e35\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e01\u0e31\u0e19\u0e40\u0e15\u0e47\u0e21\u0e22\u0e28<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e35\u0e49\u0e19\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e08\u0e31\u0e14\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e42\u0e2b\u0e2c\u0e32\u0e23\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e2a\u0e14\u0e07\u0e22\u0e38\u0e04\u0e17\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e44\u0e17\u0e22-\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19&#8221; (\u0e19\u0e32\u0e01\u0e32\u0e21\u0e39\u0e23\u0e30, 2546, 94-95)<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"429\" src=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand2-2369.jpg\" alt=\"\" class=\"wp-image-875695\" \/><figcaption class=\"wp-element-caption\"> <em>\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e42\u0e15\u0e42\u0e08\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e19\u0e32\u0e01\u0e32\u0e21\u0e39\u0e23\u0e30<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e42\u0e15\u0e42\u0e08\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e42\u0e15\u0e42\u0e08\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e44\u0e17\u0e22 \u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e08\u0e32\u0e01\u0e2b\u0e2d\u0e08\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e2b\u0e15\u0e38\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e44\u0e27\u0e49\u0e27\u0e48\u0e32 \u0e17\u0e32\u0e07\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e40\u0e07\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e44\u0e17\u0e22\u0e08\u0e33\u0e19\u0e27\u0e19 250,000 \u0e1a\u0e32\u0e17<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e07\u0e34\u0e19\u0e1a\u0e23\u0e34\u0e08\u0e32\u0e04\u0e43\u0e2b\u0e49\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e1a\u0e01 150,000 \u0e1a\u0e32\u0e17<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e19\u0e27\u0e19 50,000 \u0e1a\u0e32\u0e17<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1e\u0e38\u0e17\u0e18\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 15,000 \u0e1a\u0e32\u0e17 \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e44\u0e17\u0e22-\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 15,000 \u0e1a\u0e32\u0e17<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e15\u0e33\u0e23\u0e27\u0e08\u0e44\u0e17\u0e22 5,000 \u0e1a\u0e32\u0e17<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 10,000 \u0e1a\u0e32\u0e17<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e41\u0e25\u0e30\u0e01\u0e23\u0e21\u0e17\u0e2b\u0e32\u0e23\u0e1c\u0e2a\u0e21\u0e44\u0e17\u0e22\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 5,000 \u0e1a\u0e32\u0e17 (\u0e2b\u0e08\u0e0a. (3) \u0e01\u0e15. 1.6\/10 \u0e01\u0e25\u0e48\u0e2d\u0e07 10) \u0e1e\u0e25.\u0e2d.\u0e2e\u0e34\u0e40\u0e14\u0e01\u0e34 \u0e42\u0e15\u0e42\u0e08 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (3 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2486-19 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2487)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e40\u0e0a\u0e49\u0e32\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e04\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e42\u0e15\u0e42\u0e08\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e44\u0e17\u0e22\u0e44\u0e1b\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e42\u0e0a\u0e19\u0e31\u0e19 (\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c) \u0e41\u0e25\u0e30\u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e43\u0e19\u0e44\u0e17\u0e22\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e41\u0e16\u0e25\u0e07\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19-\u0e44\u0e17\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e2d\u0e1a 6 \u0e23\u0e31\u0e10\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e44\u0e1b\u0e17\u0e31\u0e48\u0e27\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e14\u0e35 \u0e01\u0e32\u0e23\u0e21\u0e2d\u0e1a\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e44\u0e17\u0e22\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e42\u0e14\u0e22\u0e23\u0e32\u0e1a\u0e23\u0e37\u0e48\u0e19 \u0e04\u0e19\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e47\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e17\u0e32\u0e07\u0e1d\u0e48\u0e32\u0e22\u0e1e\u0e21\u0e48\u0e32\u0e40\u0e2d\u0e07 (\u0e41\u0e16\u0e21\u0e2a\u0e38\u0e02, 2544, 117)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e01\u0e31\u0e1a\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e17\u0e22\u0e21\u0e35\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e08\u0e32\u0e01 513,120 \u0e15\u0e23.\u0e01\u0e21. \u0e40\u0e1b\u0e47\u0e19 74, 587 \u0e15\u0e23.\u0e01\u0e21.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 \u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e44\u0e17\u0e22\u0e40\u0e14\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e35\u0e48\u0e23\u0e31\u0e10\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e44\u0e17\u0e22\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e02\u0e49\u0e32\u0e2b\u0e25\u0e27\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e35\u0e48\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e0d\u0e48 1 \u0e04\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e15\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e2a\u0e35\u0e48\u0e23\u0e31\u0e10\u0e21\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e02\u0e49\u0e32\u0e2b\u0e25\u0e27\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e43\u0e2b\u0e49\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e38\u0e01\u0e23\u0e31\u0e10 (\u0e01\u0e23\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e2b\u0e32\u0e23, 2540, 216-218)<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" src=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand3-2369-1200x801.jpg\" alt=\"\" class=\"wp-image-875694\" srcset=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand3-2369-1200x801.jpg 1200w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand3-2369-768x512.jpg 768w, https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand3-2369.jpg 1379w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\"><em>\u0e08\u0e2d\u0e21\u0e1e\u0e25 \u0e1b.\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e42\u0e15\u0e42\u0e08\u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35\u0e0a\u0e31\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d 4 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2486<\/em><br><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e2a\u0e32\u0e2a\u0e4c\u0e19\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 6 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e17\u0e2a\u0e38\u0e42\u0e1a\u0e01\u0e32\u0e21\u0e34 \u0e41\u0e08\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e08\u0e2d\u0e21\u0e1e\u0e25 \u0e1b.\u0e17\u0e23\u0e32\u0e1a\u0e27\u0e48\u0e32 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e42\u0e15\u0e42\u0e08\u0e16\u0e36\u0e07\u0e42\u0e0a\u0e19\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e44\u0e14\u0e49\u0e42\u0e17\u0e23\u0e40\u0e25\u0e02\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e1d\u0e48\u0e32\u0e22\u0e44\u0e17\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e44\u0e19\u0e01\u0e32\u0e23\u0e21\u0e32\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e2a\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e09\u0e31\u0e19\u0e44\u0e14\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e1e\u0e1a\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e14\u0e49\u0e27\u0e22\u0e08\u0e34\u0e15\u0e44\u0e08\u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e19\u0e21\u0e34\u0e15\u0e23\u0e21\u0e32\u0e41\u0e15\u0e48\u0e40\u0e01\u0e48\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e2a\u0e19\u0e17\u0e19\u0e32\u0e01\u0e31\u0e1a\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e19\u0e34\u0e18\u0e2a\u0e19\u0e21\u0e44\u0e19\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e2a\u0e44\u0e17\u0e22\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e2a\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e14\u0e49\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e09\u0e31\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e1b\u0e25\u0e37\u0e49\u0e21\u0e1b\u0e34\u0e15\u0e34\u0e2b\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e38\u0e14\u0e0b\u0e36\u0e49\u0e07 \u0e44\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e1e\u0e31\u0e01\u0e2b\u0e22\u0e39\u0e48\u0e44\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e09\u0e31\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e40\u0e1f\u0e37\u0e49\u0e2d\u0e08\u0e32\u0e01\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e09\u0e31\u0e19\u0e0d\u0e32\u0e15\u0e34\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e34\u0e18\u0e40\u0e1b\u0e19\u0e2b\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e09\u0e31\u0e19\u0e08\u0e30\u0e25\u0e37\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e19\u0e2d\u0e31\u0e19\u0e02\u0e32\u0e14 \u0e09\u0e31\u0e19\u0e02\u0e2d\u0e16\u0e37\u0e2d\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e2a\u0e41\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e19\u0e21\u0e32\u0e22\u0e31\u0e07\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e09\u0e31\u0e19\u0e44\u0e14\u0e49\u0e21\u0e32\u0e16\u0e36\u0e07\u0e42\u0e0a\u0e19\u0e31\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e49\u0e27\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e34\u0e07\u0e44\u0e08\u0e44\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e21\u0e15\u0e15\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e27\u0e31\u0e07\u0e27\u0e48\u0e32 \u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e04\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e35&#8221; (\u0e2b\u0e08\u0e0a. (3) \u0e01\u0e15. 1.6\/10 \u0e01\u0e25\u0e48\u0e2d\u0e07 10) \u0e1e\u0e25.\u0e2d.\u0e2e\u0e34\u0e40\u0e14\u0e01\u0e34 \u0e42\u0e15\u0e42\u0e08 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (3 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2486-19 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2487)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e08\u0e2d\u0e21\u0e1e\u0e25 \u0e1b.\u0e15\u0e2d\u0e1a\u0e1c\u0e48\u0e32\u0e19\u0e42\u0e17\u0e23\u0e40\u0e25\u0e02\u0e01\u0e25\u0e31\u0e1a\u0e27\u0e48\u0e32<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e09\u0e31\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e40\u0e25\u0e02\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e41\u0e25\u0e30\u0e22\u0e34\u0e19\u0e14\u0e35\u0e17\u0e35\u0e48\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07\u0e41\u0e25\u0e49\u0e27\u0e42\u0e14\u0e22\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e20\u0e32\u0e1e \u0e44\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e2a\u0e21\u0e32\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e09\u0e31\u0e19\u0e2b\u0e22\u0e48\u0e32\u0e07\u0e21\u0e34\u0e15\u0e23\u0e2d\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e18\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e40\u0e1b\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e08\u0e32\u0e23\u0e36\u0e01\u0e2b\u0e22\u0e39\u0e48\u0e44\u0e19\u0e44\u0e08\u0e09\u0e31\u0e19 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e27\u0e31\u0e19\u0e25\u0e37\u0e21 \u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e44\u0e19\u0e04\u0e23\u0e32\u0e27\u0e19\u0e35\u0e49\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e27\u0e48\u0e32\u0e22\u0e31\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e2a\u0e17\u0e35\u0e48\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e2a\u0e21\u0e04\u0e27\u0e23\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2b\u0e22\u0e39\u0e48\u0e21\u0e32\u0e01 \u0e2b\u0e32\u0e01\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e44\u0e14\u0e17\u0e35\u0e48\u0e1a\u0e01\u0e1e\u0e23\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e42\u0e1b\u0e23\u0e14\u0e44\u0e2b\u0e49\u0e2d\u0e20\u0e31\u0e22\u0e14\u0e49\u0e27\u0e22\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e2d\u0e27\u0e22\u0e1e\u0e23\u0e43\u0e2b\u0e49\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e1e\u0e19\u0e30\u0e17\u0e48\u0e32\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e08\u0e07\u0e21\u0e35\u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e2b\u0e23\u0e47\u0e14\u0e14\u0e31\u0e07\u0e1b\u0e23\u0e32\u0e23\u0e16\u0e19\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23&#8221; (\u0e2b\u0e08\u0e0a. (3) \u0e01\u0e15. 1.6\/10 \u0e01\u0e25\u0e48\u0e2d\u0e07 10) \u0e1e\u0e25.\u0e2d.\u0e2e\u0e34\u0e40\u0e14\u0e01\u0e34 \u0e42\u0e15\u0e42\u0e08 \u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (3 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2486-19 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2487)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e15\u0e42\u0e08\u0e43\u0e19\u0e15\u0e49\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e14\u0e49\u0e21\u0e2d\u0e1a\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e44\u0e17\u0e22\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21\u0e21\u0e35\u0e01\u0e32\u0e23\u0e25\u0e07\u0e19\u0e32\u0e21\u0e2a\u0e19\u0e18\u0e34\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e15\u0e41\u0e14\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e21\u0e32\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e42\u0e14\u0e22\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e22\u0e2d\u0e21\u0e08\u0e33\u0e19\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e15\u0e48\u0e2d\u0e1d\u0e48\u0e32\u0e22\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 15 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2488 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e37\u0e19\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e25\u0e31\u0e1a\u0e04\u0e37\u0e19\u0e2a\u0e39\u0e48\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e41\u0e25\u0e30\u0e1d\u0e23\u0e31\u0e48\u0e07\u0e40\u0e28\u0e2a \u0e40\u0e08\u0e49\u0e32\u0e2d\u0e32\u0e13\u0e32\u0e19\u0e34\u0e04\u0e21 \u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e15\u0e48\u0e2d\u0e21\u0e32 (\u0e01\u0e23\u0e21\u0e22\u0e38\u0e17\u0e18\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e2b\u0e32\u0e23, 2540, 306)<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"725\" height=\"512\" data-id=\"875696\" src=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand5-2369.jpg\" alt=\"\" class=\"wp-image-875696\" \/><figcaption class=\"wp-element-caption\">\u0e1e\u0e25.\u0e2d.\u0e42\u0e15\u0e42\u0e08 \u0e41\u0e25\u0e30 \u0e1e\u0e25.\u0e17.\u0e19\u0e32\u0e01\u0e32\u0e21\u0e39\u0e23\u0e30<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"476\" data-id=\"875693\" src=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand4-2369.jpg\" alt=\"\" class=\"wp-image-875693\" \/><figcaption class=\"wp-element-caption\">\u0e07\u0e32\u0e19\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e42\u0e15\u0e42\u0e08\u0e21\u0e32\u0e44\u0e17\u0e22 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35\u0e0a\u0e31\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d 4 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2486<br><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"621\" height=\"583\" data-id=\"875692\" src=\"https:\/\/www.matichon.co.th\/weekly\/wp-content\/uploads\/2025\/12\/My-Country-Thailand6-2369.jpg\" alt=\"\" class=\"wp-image-875692\" \/><figcaption class=\"wp-element-caption\">\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e39\u0e48\u0e02\u0e2d\u0e07\u0e42\u0e15\u0e42\u0e08\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e1d\u0e48\u0e32\u0e22\u0e44\u0e17\u0e22 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a\u0e2f \u0e40\u0e21\u0e37\u0e48\u0e2d 5 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2486<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"th\" dir=\"ltr\">\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e09\u0e31\u0e1a\u0e44\u0e27 \u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 \u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23\u0e21\u0e15\u0e34\u0e0a\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<a href=\"https:\/\/t.co\/KYFMEpsHWj\" target=\"_blank\">https:\/\/t.co\/KYFMEpsHWj<\/a><\/p>&mdash; MatichonWeekly \u0e21\u0e15\u0e34\u0e0a\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c (@matichonweekly) <a href=\"https:\/\/twitter.com\/matichonweekly\/status\/1552197630306177024?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 27, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>My Country Thailand | \u0e13\u0e31\u0e10\u0e1e\u0e25 \u0e43\u0e08\u0e08\u0e23\u0e34\u0e07 \u0e42\u0e15\u0e42\u0e08 \u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e44\u0e17\u0e22 (\u0e08\u0e1a) [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":875698,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,10777],"tags":[27784,40847],"msn":[],"line":[466],"class_list":["post-875691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-column","category-nattapol","tag-27784","tag-40847","line-prod"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/875691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/comments?post=875691"}],"version-history":[{"count":5,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/875691\/revisions"}],"predecessor-version":[{"id":877188,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/posts\/875691\/revisions\/877188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/media\/875698"}],"wp:attachment":[{"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/media?parent=875691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/categories?post=875691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/tags?post=875691"},{"taxonomy":"msn","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/msn?post=875691"},{"taxonomy":"line","embeddable":true,"href":"https:\/\/www.matichon.co.th\/weekly\/wp-json\/wp\/v2\/line?post=875691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}